{"id":1537,"date":"2022-02-10T11:47:51","date_gmt":"2022-02-10T10:47:51","guid":{"rendered":"https:\/\/quiet-mauve-beetle.192-250-229-180.cpanel.site\/contact\/"},"modified":"2022-02-10T14:06:27","modified_gmt":"2022-02-10T13:06:27","slug":"contact","status":"publish","type":"page","link":"https:\/\/quiet-mauve-beetle.192-250-229-180.cpanel.site\/en\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\n\t<script type=\"text\/javascript\">\n  jQuery( document ).ready(function() {\n    function initialize() {\n        var styles = {\n            'flatsome':  [{\n            \"featureType\": \"administrative\",\n            \"stylers\": [\n              { \"visibility\": \"on\" }\n            ]\n          },\n          {\n            \"featureType\": \"road\",\n            \"stylers\": [\n              { \"visibility\": \"on\" },\n              { \"hue\": \"\" }\n            ]\n          },\n          {\n            \"stylers\": [\n\t\t\t  { \"visibility\": \"on\" },\n\t\t\t  { \"hue\": \"\" },\n\t\t\t  { \"saturation\": -30 }\n            ]\n          }\n        ]};\n\n        var myLatlng = new google.maps.LatLng(53.121361906869, 17.997955169486);\n        var myOptions = {\n            zoom: 11,\n            center: myLatlng,\n            mapTypeId: google.maps.MapTypeId.ROADMAP,\n            disableDefaultUI: true,\n            mapTypeId: 'flatsome',\n            draggable: true,\n            zoomControl: false,\n            zoomControlOptions: {\n              position: google.maps.ControlPosition.TOP_LEFT\n            },\n      \t\t\tmapTypeControl: false,\n            mapTypeControlOptions: {\n              position: google.maps.ControlPosition.TOP_LEFT\n            },\n      \t\t\tstreetViewControl: false,\n            streetViewControlOptions: {\n              position: google.maps.ControlPosition.TOP_LEFT\n            },\n            scrollwheel: false,\n            disableDoubleClickZoom: true\n        }\n        var map = new google.maps.Map(document.getElementById(\"map-2739694722-inner\"), myOptions);\n        var styledMapType = new google.maps.StyledMapType(styles['flatsome'], {name: 'flatsome'});\n        map.mapTypes.set('flatsome', styledMapType);\n\n        var marker = new google.maps.Marker({\n            position: myLatlng,\n            map: map,\n            title:\"\"\n        });\n    }\n\n    \/\/ Required to proceed\n    if (!(typeof google === 'object' && typeof google.maps === 'object')) {\n      return\n    }\n\n    initialize()\n    google.maps.event.addDomListener(window, 'resize', initialize);\n    });\n    <\/script>\n\n    <div class=\"google-map relative mb\" id=\"map-2739694722\">\n        <div class=\"map-height\" id=\"map-2739694722-inner\"><\/div>\n        <div id=\"map_overlay_top\"><\/div>\n        <div id=\"map_overlay_bottom\"><\/div>\n                  <div class=\"map_inner map-inner last-reset absolute x95 md-x95 lg-x95 y95 md-y95 lg-y95\">\n              \n<h3>OFFICE<\/h3>\n<p>Monday &#8211; Friday, 8:00 am &#8211; 5:30 pm<\/p>\n         <\/div>\n       \n       \n<style>\n#map-2739694722 .map-inner {\n  background-color: #fff;\n  max-width: 30%;\n}\n#map-2739694722 .map-height {\n  height: 300px;\n}\n<\/style>\n    <\/div>\n\n\t\n<div class=\"row\"  id=\"row-449428608\">\n\n\t<div id=\"col-1716131568\" class=\"col medium-6 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-normal\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >COSSACK MAIZE<\/span><b aria-hidden=\"true\"><\/b><\/h2><\/div>\n<p class=\"lead\">Representative of SPFE Company MAIS in Poland<\/p>\n<p class=\"lead\">ECG SEEDS Sp. z o.o. <\/p>\n<p class=\"lead\">D\u0142uga 16 street, 05-034 Bydgoszcz <\/p>\n<p class=\"lead\">HOTLINE +48 796 001 840<\/p>\n<p>&nbsp;<\/p>\n<div class=\"accordion\">\n\t<div id=\"accordion-3198930640\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3198930640-label\" class=\"accordion-title plain\" href=\"#accordion-item-open\" aria-expanded=\"false\" aria-controls=\"accordion-3198930640-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Open<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3198930640-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3198930640-label\">\n\t\t\t\n<p>Monday &#8211; Friday, 8:00 am &#8211; 5:30 pm<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-418105692\" class=\"col medium-6 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >Write to us<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1660-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1660\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/1537#wpcf7-f1660-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1660\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1660-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label>Name and Surname (required)<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p><label>Your email (required)<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p><label>Your phone number (required)<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-995\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-995\" \/><\/span>\n<\/p>\n<p><label>County (required)<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"text-734\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-734\" \/><\/span>\n<\/p>\n<p><label>Message (required)<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner button\" type=\"submit\" value=\"Send\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":1342,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-1537","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/quiet-mauve-beetle.192-250-229-180.cpanel.site\/en\/wp-json\/wp\/v2\/pages\/1537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quiet-mauve-beetle.192-250-229-180.cpanel.site\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/quiet-mauve-beetle.192-250-229-180.cpanel.site\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/quiet-mauve-beetle.192-250-229-180.cpanel.site\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quiet-mauve-beetle.192-250-229-180.cpanel.site\/en\/wp-json\/wp\/v2\/comments?post=1537"}],"version-history":[{"count":5,"href":"https:\/\/quiet-mauve-beetle.192-250-229-180.cpanel.site\/en\/wp-json\/wp\/v2\/pages\/1537\/revisions"}],"predecessor-version":[{"id":1548,"href":"https:\/\/quiet-mauve-beetle.192-250-229-180.cpanel.site\/en\/wp-json\/wp\/v2\/pages\/1537\/revisions\/1548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quiet-mauve-beetle.192-250-229-180.cpanel.site\/en\/wp-json\/wp\/v2\/media\/1342"}],"wp:attachment":[{"href":"https:\/\/quiet-mauve-beetle.192-250-229-180.cpanel.site\/en\/wp-json\/wp\/v2\/media?parent=1537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}